{"id":10805,"date":"2019-05-14T15:21:30","date_gmt":"2019-05-14T19:21:30","guid":{"rendered":"http:\/\/www.carl-abrc.ca\/?p=10805"},"modified":"2019-05-14T15:28:59","modified_gmt":"2019-05-14T19:28:59","slug":"mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur","status":"publish","type":"post","link":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/","title":{"rendered":"L\u2019ABRC publie une mise \u00e0 jour de l\u2019Addenda de l\u2019auteur canadien et un nouveau Guide des droits d\u2019auteur"},"content":{"rendered":"<p><strong>Ottawa, le 14 mai 2019. \u2013<\/strong> L\u2019ABRC est heureuse d\u2019annoncer la publication de trois ressources de sensibilisation aux droits de l\u2019auteur et \u00e0 des fa\u00e7ons de conserver les droits cl\u00e9s pendant le processus de publication.<\/p>\n<p>La version r\u00e9vis\u00e9e de l\u2019<em><strong><a href=\"http:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2019\/05\/Addenda_auteur_can_FR_2019.pdf\">Addenda de l\u2019auteur canadien \u00e0 l&rsquo;entente de publication<\/a><\/strong><\/em> est un outil qui peut \u00eatre utilis\u00e9 par les auteurs pour n\u00e9gocier avec les \u00e9diteurs le droit de conserver des droits importants, notamment la capacit\u00e9 de partager et r\u00e9utiliser leur \u0153uvre, y compris la capacit\u00e9 de mettre leur travail \u00e0 la disposition de tous par l\u2019interm\u00e9diaire d\u2019un d\u00e9p\u00f4t \u00e0 libre acc\u00e8s. Le <em><strong><a href=\"http:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2019\/05\/Guide_ABRC_Addenda_can_FR_2019.pdf\">Guide de l\u2019ABRC sur l\u2019utilisation de l\u2019Addenda de l\u2019auteur canadien<\/a><\/strong><\/em> offre des orientations pratiques et simples sur la mani\u00e8re d\u2019utiliser l\u2019Addenda.<\/p>\n<p>Le <em><strong><a href=\"http:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2019\/05\/Guide_ABRC_droits_auteurs_FR_2019.pdf\">Guide des droits d\u2019auteur de l&rsquo;ABRC<\/a><\/strong><\/em>\u00a0vise \u00e0 situer l\u2019utilisation de l\u2019Addenda dans le contexte plus large des droits d\u2019auteurs et de la propri\u00e9t\u00e9 des \u0153uvres savantes, y compris la mani\u00e8re dont la conservation des droits peut \u00eatre consid\u00e9r\u00e9e \u00e0 chaque \u00e9tape du cycle de vie de la publication. Ce guide peut aider les auteurs et les biblioth\u00e9caires \u00e0 savoir quand et comment utiliser l\u2019Addenda, en plus de contribuer \u00e0 une meilleure compr\u00e9hension du droit d\u2019auteur sur le plan de la cr\u00e9ation et de la diffusion de recherche savante.<\/p>\n<p><strong>Veuillez noter que <a href=\"http:\/\/www.carl-abrc.ca\/fr\/faire-avancer-la-recherche\/gt-addenda-auteurs\/\">des versions \u00e9ditables de ces documents<\/a> sont aussi disponibles.<\/strong><\/p>\n<p><strong>R\u00e9sum\u00e9 des r\u00e9visions de l\u2019Addenda de l\u2019auteur<\/strong><br \/>\nEn se fondant sur les commentaires des \u00e9tablissements membres et une reconnaissance que les auteurs ont un besoin croissant de conserver une plus grand partie de leurs droits au moment de publier afin de respecter les politiques de libre acc\u00e8s des organismes de financement comme la <a href=\"http:\/\/www.science.gc.ca\/eic\/site\/063.nsf\/fra\/h_F6765465.html\">Politique des trois organismes sur le libre acc\u00e8s aux publications<\/a> et d\u2019assurer une plus vaste distribution de leurs \u0153uvres, l\u2019ABRC a entrepris une analyse et une r\u00e9vision d\u00e9taill\u00e9es de l\u2019Addenda de l\u2019auteur canadien (initialement adapt\u00e9 en 2007 \u00e0 partir du <a href=\"https:\/\/sparcopen.org\/our-work\/author-rights\/sparc-author-addendum-text\/\">SPARC Author Addendum to Publisher Agreement<\/a>). L\u2019objectif \u00e9tait de s\u2019assurer qu\u2019il refl\u00e9tait le contexte canadien du droit d\u2019auteur actuel.<\/p>\n<p>L\u2019Addenda r\u00e9vis\u00e9 comprend deux changements importants : l\u2019inclusion d\u2019une disposition reconnaissant les octrois de licence non exclusive ant\u00e9rieurs aux \u00e9tablissements ou organismes de financement des auteurs par l\u2019interm\u00e9diaire de politiques de libre acc\u00e8s (cette disposition fait partie de l\u2019Addenda de l\u2019auteur de SPARC depuis plusieurs ann\u00e9es), ainsi que l\u2019\u00e9largissement de l\u2019Addenda afin que ce dernier puisse servir dans les n\u00e9gociations d\u2019entente de publication d\u2019un chapitre de livre aussi bien qu\u2019un article de revue.<\/p>\n<p><strong>Remerciements<\/strong><br \/>\nCe guide est le r\u00e9sultat des efforts du <a href=\"http:\/\/www.carl-abrc.ca\/fr\/faire-avancer-la-recherche\/gt-addenda-auteurs\/\">Groupe de travail sur l\u2019Addenda des auteurs et les droits d\u2019auteurs<\/a> : Lise Brin (ABRC), Rosarie Coughlan (Queen\u2019s University), Roger Gillis (Dalhousie University), Stephanie Savage (University of British Columbia) et Jennifer Zerkee (Simon Fraser University), sous la direction du Comit\u00e9 sur l\u2019avancement de la recherche de l\u2019ABRC. Sinc\u00e8res remerciements aux membres de la communaut\u00e9 canadienne et internationale des biblioth\u00e8ques et de la communication savante qui ont offert de pr\u00e9cieux renseignements et commentaires.<\/p>\n<p style=\"text-align: center;\">-30-<\/p>\n<p>Les membres de l\u2019ABRC comprennent les vingt-neuf plus grandes biblioth\u00e8ques universitaires du Canada ainsi que deux biblioth\u00e8ques nationales. L\u2019am\u00e9lioration de la recherche et de l\u2019enseignement sup\u00e9rieur est au c\u0153ur de sa mission. L\u2019ABRC d\u00e9veloppe la capacit\u00e9 d\u2019appuyer cette mission, et favorise l\u2019efficacit\u00e9 et la p\u00e9rennit\u00e9 de la communication savante, ainsi que les politiques publiques qui permettent l\u2019acc\u00e8s le plus large possible \u00e0 l\u2019information savante.<\/p>\n<p>Pour plus de renseignements, pri\u00e8re de communiquer avec :<br \/>\nLise Brin, agente de programme<br \/>\n<a href=\"mailto:lise.brin@carl-abrc.ca\">lise.brin@carl-abrc.ca<\/a><br \/>\n902-318 4485<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ottawa, le 14 mai 2019. \u2013 L\u2019ABRC est heureuse d\u2019annoncer la publication de trois ressources de sensibilisation aux droits de l\u2019auteur et \u00e0 des fa\u00e7ons de conserver les droits cl\u00e9s [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":36194,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-10805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019ABRC publie une mise \u00e0 jour de l\u2019Addenda de l\u2019auteur canadien et un nouveau Guide des droits d\u2019auteur - Association des biblioth\u00e8ques de recherche du Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019ABRC publie une mise \u00e0 jour de l\u2019Addenda de l\u2019auteur canadien et un nouveau Guide des droits d\u2019auteur - Association des biblioth\u00e8ques de recherche du Canada\" \/>\n<meta property=\"og:description\" content=\"Ottawa, le 14 mai 2019. \u2013 L\u2019ABRC est heureuse d\u2019annoncer la publication de trois ressources de sensibilisation aux droits de l\u2019auteur et \u00e0 des fa\u00e7ons de conserver les droits cl\u00e9s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/\" \/>\n<meta property=\"og:site_name\" content=\"Association des biblioth\u00e8ques de recherche du Canada\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-14T19:21:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-14T19:28:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CARL ABRC\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CARL ABRC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\\\/\"},\"author\":{\"name\":\"CARL ABRC\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/person\\\/98e5fc089af8c90ef31f178793d7f5d1\"},\"headline\":\"L\u2019ABRC publie une mise \u00e0 jour de l\u2019Addenda de l\u2019auteur canadien et un nouveau Guide des droits d\u2019auteur\",\"datePublished\":\"2019-05-14T19:21:30+00:00\",\"dateModified\":\"2019-05-14T19:28:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\\\/\"},\"wordCount\":677,\"publisher\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/NewsFeaturedImage-1.jpg\",\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\\\/\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\\\/\",\"name\":\"L\u2019ABRC publie une mise \u00e0 jour de l\u2019Addenda de l\u2019auteur canadien et un nouveau Guide des droits d\u2019auteur - Association des biblioth\u00e8ques de recherche du Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/NewsFeaturedImage-1.jpg\",\"datePublished\":\"2019-05-14T19:21:30+00:00\",\"dateModified\":\"2019-05-14T19:28:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/NewsFeaturedImage-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/NewsFeaturedImage-1.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"C.A.R.L. Logo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/home-3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019ABRC publie une mise \u00e0 jour de l\u2019Addenda de l\u2019auteur canadien et un nouveau Guide des droits d\u2019auteur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/\",\"name\":\"Association des biblioth\u00e8ques de recherche du Canada\",\"description\":\"ABRC\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\",\"name\":\"Association des biblioth\u00e8ques de recherche du Canada\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Stacked_Colour_L.png\",\"contentUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Stacked_Colour_L.png\",\"width\":641,\"height\":250,\"caption\":\"Association des biblioth\u00e8ques de recherche du Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/carlabrc\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/person\\\/98e5fc089af8c90ef31f178793d7f5d1\",\"name\":\"CARL ABRC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2c9b376bd4002fbd30a8b9425e697c0b60aeef1966421e6ee3f5d8137228c29?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2c9b376bd4002fbd30a8b9425e697c0b60aeef1966421e6ee3f5d8137228c29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2c9b376bd4002fbd30a8b9425e697c0b60aeef1966421e6ee3f5d8137228c29?s=96&d=mm&r=g\",\"caption\":\"CARL ABRC\"},\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/author\\\/infocarl-abrc-ca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019ABRC publie une mise \u00e0 jour de l\u2019Addenda de l\u2019auteur canadien et un nouveau Guide des droits d\u2019auteur - Association des biblioth\u00e8ques de recherche du Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019ABRC publie une mise \u00e0 jour de l\u2019Addenda de l\u2019auteur canadien et un nouveau Guide des droits d\u2019auteur - Association des biblioth\u00e8ques de recherche du Canada","og_description":"Ottawa, le 14 mai 2019. \u2013 L\u2019ABRC est heureuse d\u2019annoncer la publication de trois ressources de sensibilisation aux droits de l\u2019auteur et \u00e0 des fa\u00e7ons de conserver les droits cl\u00e9s [&hellip;]","og_url":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/","og_site_name":"Association des biblioth\u00e8ques de recherche du Canada","article_published_time":"2019-05-14T19:21:30+00:00","article_modified_time":"2019-05-14T19:28:59+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","type":"image\/jpeg"}],"author":"CARL ABRC","twitter_misc":{"\u00c9crit par":"CARL ABRC","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/#article","isPartOf":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/"},"author":{"name":"CARL ABRC","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/person\/98e5fc089af8c90ef31f178793d7f5d1"},"headline":"L\u2019ABRC publie une mise \u00e0 jour de l\u2019Addenda de l\u2019auteur canadien et un nouveau Guide des droits d\u2019auteur","datePublished":"2019-05-14T19:21:30+00:00","dateModified":"2019-05-14T19:28:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/"},"wordCount":677,"publisher":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization"},"image":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/","url":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/","name":"L\u2019ABRC publie une mise \u00e0 jour de l\u2019Addenda de l\u2019auteur canadien et un nouveau Guide des droits d\u2019auteur - Association des biblioth\u00e8ques de recherche du Canada","isPartOf":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/#primaryimage"},"image":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","datePublished":"2019-05-14T19:21:30+00:00","dateModified":"2019-05-14T19:28:59+00:00","breadcrumb":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/#primaryimage","url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","contentUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","width":1920,"height":1080,"caption":"C.A.R.L. Logo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/mise-a-jour-addenda-de-lauteur-canadien-et-guide-des-droits-dauteur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carl-abrc.ca\/fr\/home-3\/"},{"@type":"ListItem","position":2,"name":"L\u2019ABRC publie une mise \u00e0 jour de l\u2019Addenda de l\u2019auteur canadien et un nouveau Guide des droits d\u2019auteur"}]},{"@type":"WebSite","@id":"https:\/\/www.carl-abrc.ca\/fr\/#website","url":"https:\/\/www.carl-abrc.ca\/fr\/","name":"Association des biblioth\u00e8ques de recherche du Canada","description":"ABRC","publisher":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carl-abrc.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization","name":"Association des biblioth\u00e8ques de recherche du Canada","url":"https:\/\/www.carl-abrc.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/07\/cropped-Stacked_Colour_L.png","contentUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/07\/cropped-Stacked_Colour_L.png","width":641,"height":250,"caption":"Association des biblioth\u00e8ques de recherche du Canada"},"image":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/carlabrc"]},{"@type":"Person","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/person\/98e5fc089af8c90ef31f178793d7f5d1","name":"CARL ABRC","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c2c9b376bd4002fbd30a8b9425e697c0b60aeef1966421e6ee3f5d8137228c29?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c2c9b376bd4002fbd30a8b9425e697c0b60aeef1966421e6ee3f5d8137228c29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c2c9b376bd4002fbd30a8b9425e697c0b60aeef1966421e6ee3f5d8137228c29?s=96&d=mm&r=g","caption":"CARL ABRC"},"url":"https:\/\/www.carl-abrc.ca\/fr\/author\/infocarl-abrc-ca\/"}]}},"_links":{"self":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts\/10805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/comments?post=10805"}],"version-history":[{"count":0,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts\/10805\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/media\/36194"}],"wp:attachment":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/media?parent=10805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/categories?post=10805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/tags?post=10805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}