{"id":2326,"date":"2016-02-03T13:56:35","date_gmt":"2016-02-03T18:56:35","guid":{"rendered":"http:\/\/www.carl-abrc.ca\/fr\/?p=2326"},"modified":"2016-04-08T14:05:06","modified_gmt":"2016-04-08T18:05:06","slug":"couts-des-revues","status":"publish","type":"post","link":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/couts-des-revues\/","title":{"rendered":"La chute du dollar canadien soul\u00e8ve le probl\u00e8me de longue date des co\u00fbts des revues"},"content":{"rendered":"<p><strong>OTTAWA, le 3 f\u00e9vrier, 2016 \u2013<\/strong> Les biblioth\u00e8ques de recherche dans l\u2019ensemble du pays connaissent de graves contraintes budg\u00e9taires en raison de l\u2019affaiblissement du dollar canadien et des co\u00fbts extraordinairement \u00e9lev\u00e9s des revues savantes internationales.<\/p>\n<h2>Contexte<\/h2>\n<p>Les biblioth\u00e8ques universitaires s\u2019efforcent de fournir aux professeurs, aux scientifiques et aux \u00e9tudiants des universit\u00e9s un vaste acc\u00e8s \u00e0 l\u2019information savante internationale, reconnaissant que la recherche publi\u00e9e est le point de d\u00e9part incontournable qui inspire la nouvelle recherche, et vient ensuite engendrer de nouvelles connaissances qui permettent de faire avancer la science, la culture et la soci\u00e9t\u00e9. Une bonne part de la recherche mondiale est pr\u00e9sent\u00e9e dans des articles publi\u00e9s dans des revues dont la plupart se consultent en ligne par voie d\u2019abonnement.<\/p>\n<p>Une biblioth\u00e8que de recherche typique s\u2019abonne \u00e0 des dizaines de milliers de revues. Les revues diffus\u00e9es par abonnement sont de plus en plus d\u00e9tenues par un petit nombre d\u2019\u00e9diteurs internationaux, et sont habituellement vendues aux biblioth\u00e8ques sous forme de titres group\u00e9s (de la m\u00eame fa\u00e7on que les forfaits de cha\u00eenes t\u00e9l\u00e9 sur le c\u00e2ble). Il est parfois possible d\u2019acheter des abonnements individuels aux revues, mais m\u00eame en\u00a0 s\u2019abonnant qu\u2019\u00e0 quelques revues d\u2019une collection les \u00e9conomies sont souvent n\u00e9gligeables.<\/p>\n<p>Ce ne sont pas toutes les revues qui exigent des abonnements\u00a0: les revues \u00e0 libre acc\u00e8s (LA) fonctionnent selon un mod\u00e8le d\u2019affaires diff\u00e9rent et comptent sur d\u2019autres moyens de soutien financier. \u00c0 l\u2019heure actuelle, pr\u00e8s de 34\u00a0550 revues savantes examin\u00e9es par les pairs sont publi\u00e9es \u00e0 l\u2019\u00e9chelle mondiale et environ 30\u00a0% d\u2019entre elles sont \u00e0 libre acc\u00e8s; cependant, elles n\u2019offrent qu\u2019environ 12\u00a0% des articles examin\u00e9s par les pairs qui sont publi\u00e9s.<\/p>\n<h2>Co\u00fbts des revues<\/h2>\n<p>Les abonnements aux revues co\u00fbtent tr\u00e8s cher. En 2011, les 29 biblioth\u00e8ques de recherche universitaires membres de l&rsquo;ABRC ont d\u00e9bours\u00e9 collectivement 167\u00a0289\u00a0860\u00a0dollars canadiens pour des abonnements \u00e0 du contenu \u00e9lectronique (des revues en bonne partie). En 2014, ces d\u00e9penses ont atteint 215\u00a0224\u00a0792\u00a0dollars canadiens. Plus de 90\u00a0% de ces abonnements sont pay\u00e9s en devises \u00e9trang\u00e8res. Cette ann\u00e9e, en raison des prix \u00e0 la hausse, de la baisse du dollar et du pouvoir d\u2019achat cons\u00e9quemment r\u00e9duit des biblioth\u00e8ques, ces m\u00eames abonnements co\u00fbteront probablement plus de 260\u00a0millions\u00a0de dollars.<\/p>\n<p>Aux prises avec des d\u00e9ficits budg\u00e9taires projet\u00e9s, les biblioth\u00e8ques universitaires consultent leurs chercheurs afin de tenter de r\u00e9duire leurs frais d\u2019abonnement et de contrebalancer leur pouvoir d\u2019achat r\u00e9duit. Trois options s\u2019offrent \u00e0 elles\u00a0: l\u2019annulation des abonnements group\u00e9s en faveur de l\u2019achat d\u2019acc\u00e8s \u00e0 la pi\u00e8ce \u00e0 des revues de grande qualit\u00e9 (bien qu\u2019il ne s\u2019agisse peut\u2011\u00eatre pas l\u00e0 d\u2019une strat\u00e9gie rentable pour de nombreuses biblioth\u00e8ques), l\u2019annulation d\u2019abonnements ou de titres group\u00e9s et l\u2019obtention d\u2019articles sur demande aupr\u00e8s de d\u00e9p\u00f4ts \u00e0 libre acc\u00e8s, d\u2019autres biblioth\u00e8ques ou de fournisseurs ou l\u2019acc\u00e8s \u00e0 des revues par le truchement d\u2019ensembles constitu\u00e9s par des agr\u00e9gateurs qui ne comprennent habituellement pas les douze num\u00e9ros les plus r\u00e9cents des revues.<\/p>\n<p>Bref, il y a une parfaite temp\u00eate de facteurs en jeu, \u00e0 savoir\u00a0:<\/p>\n<ul>\n<li>de 90\u00a0\u00e0\u00a095\u00a0% des abonnements \u00e0 des revues sont pay\u00e9s en devises \u00e9trang\u00e8res, ce qui engendre d\u2019\u00e9normes d\u00e9ficits quand le dollar canadien est faible;<\/li>\n<li>les budgets des biblioth\u00e8ques de recherche sont stables ou \u00e0 la baisse;<\/li>\n<li>les abonnements sont surtout vendus sous forme de titres group\u00e9s dans lesquels une fraction du forfait est constitu\u00e9 de grandes revues;<\/li>\n<li>les titres group\u00e9s exigent souvent un engagement pluriannuel, laissant ainsi aux biblioth\u00e8ques tr\u00e8s peu de contr\u00f4le pour remanier leurs budgets en temps de crise;<\/li>\n<li>les professeurs des universit\u00e9s doivent avoir acc\u00e8s \u00e0 la recherche de pointe afin de participer pleinement au cycle de la recherche;<\/li>\n<li>quelques \u00e9diteurs internationaux d\u00e9tiennent une portion de plus en plus importante du march\u00e9 des revues et exigent des prix exag\u00e9r\u00e9s.<\/li>\n<\/ul>\n<h2>Le c\u0153ur du probl\u00e8me\u00a0: le gonflement des prix des revues<\/h2>\n<p>S\u2019il est vrai que la chute du dollar a peut-\u00eatre pr\u00e9cipit\u00e9 la crise actuelle, les budgets des biblioth\u00e8ques sont sous contraintes depuis un certain temps. Les co\u00fbts des revues ont augment\u00e9 de fa\u00e7on soutenue au cours des derni\u00e8res ann\u00e9es. EBSCO, l\u2019un des plus grands distributeurs de l\u2019industrie des abonnements aux revues, signale qu\u2019entre 2011 et 2015, les prix des p\u00e9riodiques universitaires ont augment\u00e9 de 5\u00a0\u00e0 7\u00a0% par ann\u00e9e, soit quelque 25\u00a0% au cours de cette p\u00e9riode de quatre\u00a0ans. Les biblioth\u00e8ques acad\u00e9miques du Canada s\u2019en sont un peu mieux sorties gr\u00e2ce aux consortiums nationaux et r\u00e9gionaux, qui ont su att\u00e9nuer ces augmentations de l\u2019ordre de 3 \u00e0 5 % par ann\u00e9e. L\u2019augmentation projet\u00e9e de cette ann\u00e9e est conforme \u00e0 celles des derni\u00e8res ann\u00e9es, mais additionn\u00e9e au taux de change, elle pourrait repr\u00e9senter une augmentation de 20 % des co\u00fbts ou plus \u2013 en une ann\u00e9e \u2013 pour les \u00e9tablissements canadiens.<\/p>\n<p>De r\u00e9cents travaux de recherche montrent que les prix des revues sont beaucoup plus \u00e9lev\u00e9s que le co\u00fbt r\u00e9el de leur publication. Les cinq principaux \u00e9diteurs, qui contr\u00f4lent plus de 50\u00a0% du march\u00e9, et plus de 70\u00a0% dans certaines disciplines, enregistrent une marge b\u00e9n\u00e9ficiaire de l\u2019ordre de 28\u00a0\u00e0\u00a038,9\u00a0% dans leurs divisions des revues savantes, ce qui les rapproche \u00e9troitement du chef de file de l\u2019industrie pharmaceutique, Pfizer (42\u00a0%) et leur permet de d\u00e9passer largement des g\u00e9ants comme Disney (14\u00a0%) ou Toyota (7\u00a0%). Par ailleurs, les chercheurs constatent que les frais de publication en acc\u00e8s libre constituent des frais nettement inf\u00e9rieurs pour la publication de travaux de recherche. Il devient de plus en plus clair que le syst\u00e8me de publication par abonnement est tout simplement insoutenable.<\/p>\n<p>De nouveaux mod\u00e8les pour la diffusion de l\u2019information savante, y compris le libre acc\u00e8s, s\u2019imposent. Sans un investissement dans des moyens de rechange pour la communication de l\u2019information savante, les contributions \u00e0 la science et \u00e0 la recherche du Canada risquent d\u2019\u00eatre s\u00e9rieusement entrav\u00e9es par la perte d\u2019acc\u00e8s \u00e0 la recherche qui r\u00e9sultera de la disparition \u00e0 grande \u00e9chelle de revues dans les \u00e9tablissements d\u2019enseignement canadiens.<\/p>\n<p>\u00ab\u00a0La situation constitue un probl\u00e8me auquel toutes les universit\u00e9s canadiennes doivent s\u2019attaquer,\u00a0\u00bb de dire Martha\u00a0Whitehead, pr\u00e9sidente de l\u2019ABRC ainsi que vice\u2011provost et biblioth\u00e9caire \u00e0 la Queen\u2019s University. \u00ab\u00a0Nous tenons \u00e0 offrir \u00e0 nos scientifiques les grandes revues internationales, mais nous nous devons \u00e9galement de signaler aux \u00e9diteurs qu\u2019il y a des limites quant aux fonds publics que les biblioth\u00e8ques de recherche \u2013 le principal march\u00e9 pour de telles revues \u2013 sont pr\u00eates et en mesure de d\u00e9penser\u00a0\u00bb, ajoute\u2011t\u2011elle.<\/p>\n<p style=\"text-align: center;\">&#8211; 30 &#8211;<\/p>\n<p>Les membres de<strong> l\u2019Association des biblioth\u00e8ques de recherche du Canada (ABRC)<\/strong> comprennent les vingt-neuf plus grandes biblioth\u00e8ques universitaires du Canada ainsi que Biblioth\u00e8que et Archives Canada et Gestion du savoir du Conseil national de recherches du Canada (CNRC). L\u2019am\u00e9lioration de la recherche et de l\u2019enseignement sup\u00e9rieur sont au c\u0153ur de la mission de l\u2019ABRC. Celle-ci favorise l\u2019efficacit\u00e9 et la p\u00e9rennit\u00e9 de la communication savante, ainsi que les politiques publiques qui permettent l\u2019acc\u00e8s le plus large possible \u00e0 l\u2019information savante.<\/p>\n<p>Pour de plus amples renseignements, veuillez communiquer avec<\/p>\n<p>Susan Haigh, directrice g\u00e9n\u00e9rale<br \/>\n<a href=\"mailto:Susan.haigh@carl-abrc.ca\">Susan.haigh@carl-abrc.ca<\/a><br \/>\n613-482-9344. p.101<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OTTAWA, le 3 f\u00e9vrier, 2016 \u2013 Les biblioth\u00e8ques de recherche dans l\u2019ensemble du pays connaissent de graves contraintes budg\u00e9taires en raison de l\u2019affaiblissement du dollar canadien et des co\u00fbts extraordinairement [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2326","post","type-post","status-publish","format-standard","hentry","category-nouvelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La chute du dollar canadien soul\u00e8ve le probl\u00e8me de longue date des co\u00fbts des revues - Association des biblioth\u00e8ques de recherche du Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/couts-des-revues\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La chute du dollar canadien soul\u00e8ve le probl\u00e8me de longue date des co\u00fbts des revues - Association des biblioth\u00e8ques de recherche du Canada\" \/>\n<meta property=\"og:description\" content=\"OTTAWA, le 3 f\u00e9vrier, 2016 \u2013 Les biblioth\u00e8ques de recherche dans l\u2019ensemble du pays connaissent de graves contraintes budg\u00e9taires en raison de l\u2019affaiblissement du dollar canadien et des co\u00fbts extraordinairement [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/couts-des-revues\/\" \/>\n<meta property=\"og:site_name\" content=\"Association des biblioth\u00e8ques de recherche du Canada\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-03T18:56:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-08T18:05:06+00:00\" \/>\n<meta name=\"author\" content=\"CARL ABRC\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CARL ABRC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/couts-des-revues\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/couts-des-revues\\\/\"},\"author\":{\"name\":\"CARL ABRC\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/person\\\/98e5fc089af8c90ef31f178793d7f5d1\"},\"headline\":\"La chute du dollar canadien soul\u00e8ve le probl\u00e8me de longue date des co\u00fbts des revues\",\"datePublished\":\"2016-02-03T18:56:35+00:00\",\"dateModified\":\"2016-04-08T18:05:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/couts-des-revues\\\/\"},\"wordCount\":1307,\"publisher\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\"},\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/couts-des-revues\\\/\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/couts-des-revues\\\/\",\"name\":\"La chute du dollar canadien soul\u00e8ve le probl\u00e8me de longue date des co\u00fbts des revues - Association des biblioth\u00e8ques de recherche du Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#website\"},\"datePublished\":\"2016-02-03T18:56:35+00:00\",\"dateModified\":\"2016-04-08T18:05:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/couts-des-revues\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/couts-des-revues\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/couts-des-revues\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/home-3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La chute du dollar canadien soul\u00e8ve le probl\u00e8me de longue date des co\u00fbts des revues\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/\",\"name\":\"Association des biblioth\u00e8ques de recherche du Canada\",\"description\":\"ABRC\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\",\"name\":\"Association des biblioth\u00e8ques de recherche du Canada\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Stacked_Colour_L.png\",\"contentUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Stacked_Colour_L.png\",\"width\":641,\"height\":250,\"caption\":\"Association des biblioth\u00e8ques de recherche du Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/carlabrc\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/person\\\/98e5fc089af8c90ef31f178793d7f5d1\",\"name\":\"CARL ABRC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2c9b376bd4002fbd30a8b9425e697c0b60aeef1966421e6ee3f5d8137228c29?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2c9b376bd4002fbd30a8b9425e697c0b60aeef1966421e6ee3f5d8137228c29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2c9b376bd4002fbd30a8b9425e697c0b60aeef1966421e6ee3f5d8137228c29?s=96&d=mm&r=g\",\"caption\":\"CARL ABRC\"},\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/author\\\/infocarl-abrc-ca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La chute du dollar canadien soul\u00e8ve le probl\u00e8me de longue date des co\u00fbts des revues - Association des biblioth\u00e8ques de recherche du Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/couts-des-revues\/","og_locale":"fr_FR","og_type":"article","og_title":"La chute du dollar canadien soul\u00e8ve le probl\u00e8me de longue date des co\u00fbts des revues - Association des biblioth\u00e8ques de recherche du Canada","og_description":"OTTAWA, le 3 f\u00e9vrier, 2016 \u2013 Les biblioth\u00e8ques de recherche dans l\u2019ensemble du pays connaissent de graves contraintes budg\u00e9taires en raison de l\u2019affaiblissement du dollar canadien et des co\u00fbts extraordinairement [&hellip;]","og_url":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/couts-des-revues\/","og_site_name":"Association des biblioth\u00e8ques de recherche du Canada","article_published_time":"2016-02-03T18:56:35+00:00","article_modified_time":"2016-04-08T18:05:06+00:00","author":"CARL ABRC","twitter_misc":{"\u00c9crit par":"CARL ABRC","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/couts-des-revues\/#article","isPartOf":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/couts-des-revues\/"},"author":{"name":"CARL ABRC","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/person\/98e5fc089af8c90ef31f178793d7f5d1"},"headline":"La chute du dollar canadien soul\u00e8ve le probl\u00e8me de longue date des co\u00fbts des revues","datePublished":"2016-02-03T18:56:35+00:00","dateModified":"2016-04-08T18:05:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/couts-des-revues\/"},"wordCount":1307,"publisher":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization"},"articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/couts-des-revues\/","url":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/couts-des-revues\/","name":"La chute du dollar canadien soul\u00e8ve le probl\u00e8me de longue date des co\u00fbts des revues - Association des biblioth\u00e8ques de recherche du Canada","isPartOf":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#website"},"datePublished":"2016-02-03T18:56:35+00:00","dateModified":"2016-04-08T18:05:06+00:00","breadcrumb":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/couts-des-revues\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/couts-des-revues\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/couts-des-revues\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carl-abrc.ca\/fr\/home-3\/"},{"@type":"ListItem","position":2,"name":"La chute du dollar canadien soul\u00e8ve le probl\u00e8me de longue date des co\u00fbts des revues"}]},{"@type":"WebSite","@id":"https:\/\/www.carl-abrc.ca\/fr\/#website","url":"https:\/\/www.carl-abrc.ca\/fr\/","name":"Association des biblioth\u00e8ques de recherche du Canada","description":"ABRC","publisher":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carl-abrc.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization","name":"Association des biblioth\u00e8ques de recherche du Canada","url":"https:\/\/www.carl-abrc.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/07\/cropped-Stacked_Colour_L.png","contentUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/07\/cropped-Stacked_Colour_L.png","width":641,"height":250,"caption":"Association des biblioth\u00e8ques de recherche du Canada"},"image":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/carlabrc"]},{"@type":"Person","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/person\/98e5fc089af8c90ef31f178793d7f5d1","name":"CARL ABRC","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c2c9b376bd4002fbd30a8b9425e697c0b60aeef1966421e6ee3f5d8137228c29?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c2c9b376bd4002fbd30a8b9425e697c0b60aeef1966421e6ee3f5d8137228c29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c2c9b376bd4002fbd30a8b9425e697c0b60aeef1966421e6ee3f5d8137228c29?s=96&d=mm&r=g","caption":"CARL ABRC"},"url":"https:\/\/www.carl-abrc.ca\/fr\/author\/infocarl-abrc-ca\/"}]}},"_links":{"self":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts\/2326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/comments?post=2326"}],"version-history":[{"count":0,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts\/2326\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/media?parent=2326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/categories?post=2326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/tags?post=2326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}