{"id":27540,"date":"2021-04-01T10:47:15","date_gmt":"2021-04-01T14:47:15","guid":{"rendered":"https:\/\/www.carl-abrc.ca\/?p=27540"},"modified":"2021-04-01T10:48:11","modified_gmt":"2021-04-01T14:48:11","slug":"le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada","status":"publish","type":"post","link":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\/","title":{"rendered":"Le r\u00e9seau Portage se joint \u00e0 la NOIRN pour continuer de faire progresser la GDR au Canada"},"content":{"rendered":"<p>1<sup>er<\/sup> avril 2021. \u2013 L\u2019Association des biblioth\u00e8ques de recherche du Canada (ABRC) se r\u00e9jouit d\u2019annoncer qu\u2019\u00e0 compter d\u2019aujourd\u2019hui, les activit\u00e9s de Portage, y compris son secr\u00e9tariat national, sont pleinement int\u00e9gr\u00e9es \u00e0 la Nouvelle organisation d\u2019infrastructure de recherche num\u00e9rique (NOIRN).<\/p>\n<p>L\u2019ABRC a lanc\u00e9 Portage en 2015 pour contribuer \u00e0 l\u2019intendance commune des donn\u00e9es de recherche et pallier certaines lacunes dans l\u2019infrastructure nationale de gestion des donn\u00e9es de recherche (GDR) au Canada. \u00c9tant originalement con\u00e7u en tant que r\u00e9seau ancr\u00e9 dans les biblioth\u00e8ques, Portage comporte des intervenants et des partenaires de diff\u00e9rents domaines sur le plan local, national et international pour renforcer la capacit\u00e9 ainsi que cr\u00e9er des services et de l\u2019infrastructure.<\/p>\n<p>En tant que composante des op\u00e9rations de la NOIRN, Portage continuera d\u2019appuyer la gestion des donn\u00e9es de recherche \u00e0 l\u2019\u00e9chelle nationale par des plateformes, des services, des outils, de la mobilisation ainsi que de la formation en mati\u00e8re d\u2019intendance. <span style=\"text-decoration: underline;\"><a href=\"https:\/\/portagenetwork.ca\/fr\/nouvelles\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gestion-des-donnees-de-recherche-au-canada\/\">Le transfert annonc\u00e9 aujourd&rsquo;hui<\/a><\/span> s\u2019appuie sur une <span style=\"text-decoration: underline;\"><a href=\"https:\/\/portagenetwork.ca\/fr\/nouvelles\/nouvelle-entente-entre-la-noirn-et-labrc-en-appui-a-portage-et-a-la-gestion-des-donnees-de-recherche-au-canada\/\">entente entre l\u2019ABRC et la NOIRN<\/a><\/span> pour appuyer Portage et la GDR au Canada<\/p>\n<p>La communaut\u00e9 des biblioth\u00e8ques de recherche est fi\u00e8re d&rsquo;avoir lanc\u00e9 et soutenu le travail de base de Portage pour faire progresser les meilleures pratiques et les outils d&rsquo;infrastructure nationale de GDR, et de voir Portage recevoir le soutien du gouvernement du Canada par l&rsquo;interm\u00e9diaire de la NOIRN.<\/p>\n<p>Bien que Portage soit le r\u00e9sultat d&rsquo;un effort largement diffus\u00e9 comprenant de nombreuses personnes d\u00e9vou\u00e9es, des groupes d&rsquo;experts et deux comit\u00e9s directeurs, nous tenons particuli\u00e8rement \u00e0 remercier Jeff Moon, l&rsquo;actuel directeur de Portage, et Chuck Humphry, le premier directeur, pour leur vision et leadership d\u00e9vou\u00e9 \u00e0 la croissance remarquable de Portage et ses nombreuses r\u00e9alisations. Nous nous r\u00e9jouissons \u00e0 l\u2019id\u00e9e de l&rsquo;\u00e9lan continu du d\u00e9veloppement des services, de l&rsquo;infrastructure, des outils et de la formation en mati\u00e8re de GDR \u00e0 l&rsquo;appui des chercheurs canadiens, et de l&rsquo;int\u00e9gration de ces activit\u00e9s dans la strat\u00e9gie de l&rsquo;infrastructure de recherche num\u00e9rique \u00e9largie.<\/p>\n<p><strong>\u00c0 propos de CARL :<\/strong> L\u2019ABRC est la voie des biblioth\u00e8ques de recherche canadiennes. Elle est compos\u00e9e des 29 plus grandes biblioth\u00e8ques universitaires et de deux \u00e9tablissements f\u00e9d\u00e9raux. L\u2019ABRC am\u00e9liore leur contribution \u00e0 la recherche et \u00e0 l\u2019enseignement sup\u00e9rieur\u2009; elle favorise l\u2019efficacit\u00e9 et la p\u00e9rennit\u00e9 de la cr\u00e9ation, de la diffusion et de la pr\u00e9servation de connaissances\u2009; elle d\u00e9fend la mise en \u0153uvre de politiques publiques garantissant un acc\u00e8s \u00e9largi \u00e0 l\u2019information savante.<\/p>\n<p><strong>Coordonn\u00e9es m\u00e9diatiques :<\/strong><\/p>\n<p>Susan Haigh<br \/>\nDirectrice g\u00e9n\u00e9rale, ABRC<br \/>\n<span style=\"text-decoration: underline;\"><a href=\"mailto:susan.haigh@carl-abrc.ca\">susan.haigh@carl-abrc.ca<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1er avril 2021. \u2013 L\u2019Association des biblioth\u00e8ques de recherche du Canada (ABRC) se r\u00e9jouit d\u2019annoncer qu\u2019\u00e0 compter d\u2019aujourd\u2019hui, les activit\u00e9s de Portage, y compris son secr\u00e9tariat national, sont pleinement int\u00e9gr\u00e9es [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-27540","post","type-post","status-publish","format-standard","hentry","category-nouvelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le r\u00e9seau Portage se joint \u00e0 la NOIRN pour continuer de faire progresser la GDR au Canada - Association des biblioth\u00e8ques de recherche du Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le r\u00e9seau Portage se joint \u00e0 la NOIRN pour continuer de faire progresser la GDR au Canada - Association des biblioth\u00e8ques de recherche du Canada\" \/>\n<meta property=\"og:description\" content=\"1er avril 2021. \u2013 L\u2019Association des biblioth\u00e8ques de recherche du Canada (ABRC) se r\u00e9jouit d\u2019annoncer qu\u2019\u00e0 compter d\u2019aujourd\u2019hui, les activit\u00e9s de Portage, y compris son secr\u00e9tariat national, sont pleinement int\u00e9gr\u00e9es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\/\" \/>\n<meta property=\"og:site_name\" content=\"Association des biblioth\u00e8ques de recherche du Canada\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-01T14:47:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-01T14:48:11+00:00\" \/>\n<meta name=\"author\" content=\"Julie Morin\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julie Morin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\\\/\"},\"author\":{\"name\":\"Julie Morin\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/person\\\/d9b6bfb73c89f6e9eafbd338013764ed\"},\"headline\":\"Le r\u00e9seau Portage se joint \u00e0 la NOIRN pour continuer de faire progresser la GDR au Canada\",\"datePublished\":\"2021-04-01T14:47:15+00:00\",\"dateModified\":\"2021-04-01T14:48:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\\\/\"},\"wordCount\":484,\"publisher\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\"},\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\\\/\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\\\/\",\"name\":\"Le r\u00e9seau Portage se joint \u00e0 la NOIRN pour continuer de faire progresser la GDR au Canada - Association des biblioth\u00e8ques de recherche du Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#website\"},\"datePublished\":\"2021-04-01T14:47:15+00:00\",\"dateModified\":\"2021-04-01T14:48:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le r\u00e9seau Portage se joint \u00e0 la NOIRN pour continuer de faire progresser la GDR au Canada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/\",\"name\":\"Association des biblioth\u00e8ques de recherche du Canada\",\"description\":\"ABRC\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\",\"name\":\"Association des biblioth\u00e8ques de recherche du Canada\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Stacked_Colour_L.png\",\"contentUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Stacked_Colour_L.png\",\"width\":641,\"height\":250,\"caption\":\"Association des biblioth\u00e8ques de recherche du Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/carlabrc\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/person\\\/d9b6bfb73c89f6e9eafbd338013764ed\",\"name\":\"Julie Morin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f563df894a5ea8e4663aea014d75f7ff272a49a318995c22006e48ba2fca63e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f563df894a5ea8e4663aea014d75f7ff272a49a318995c22006e48ba2fca63e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f563df894a5ea8e4663aea014d75f7ff272a49a318995c22006e48ba2fca63e?s=96&d=mm&r=g\",\"caption\":\"Julie Morin\"},\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/author\\\/julie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le r\u00e9seau Portage se joint \u00e0 la NOIRN pour continuer de faire progresser la GDR au Canada - Association des biblioth\u00e8ques de recherche du Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\/","og_locale":"fr_FR","og_type":"article","og_title":"Le r\u00e9seau Portage se joint \u00e0 la NOIRN pour continuer de faire progresser la GDR au Canada - Association des biblioth\u00e8ques de recherche du Canada","og_description":"1er avril 2021. \u2013 L\u2019Association des biblioth\u00e8ques de recherche du Canada (ABRC) se r\u00e9jouit d\u2019annoncer qu\u2019\u00e0 compter d\u2019aujourd\u2019hui, les activit\u00e9s de Portage, y compris son secr\u00e9tariat national, sont pleinement int\u00e9gr\u00e9es [&hellip;]","og_url":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\/","og_site_name":"Association des biblioth\u00e8ques de recherche du Canada","article_published_time":"2021-04-01T14:47:15+00:00","article_modified_time":"2021-04-01T14:48:11+00:00","author":"Julie Morin","twitter_misc":{"\u00c9crit par":"Julie Morin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\/#article","isPartOf":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\/"},"author":{"name":"Julie Morin","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/person\/d9b6bfb73c89f6e9eafbd338013764ed"},"headline":"Le r\u00e9seau Portage se joint \u00e0 la NOIRN pour continuer de faire progresser la GDR au Canada","datePublished":"2021-04-01T14:47:15+00:00","dateModified":"2021-04-01T14:48:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\/"},"wordCount":484,"publisher":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization"},"articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\/","url":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\/","name":"Le r\u00e9seau Portage se joint \u00e0 la NOIRN pour continuer de faire progresser la GDR au Canada - Association des biblioth\u00e8ques de recherche du Canada","isPartOf":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#website"},"datePublished":"2021-04-01T14:47:15+00:00","dateModified":"2021-04-01T14:48:11+00:00","breadcrumb":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/le-reseau-portage-se-joint-a-la-noirn-pour-continuer-de-faire-progresser-la-gdr-au-canada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carl-abrc.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Le r\u00e9seau Portage se joint \u00e0 la NOIRN pour continuer de faire progresser la GDR au Canada"}]},{"@type":"WebSite","@id":"https:\/\/www.carl-abrc.ca\/fr\/#website","url":"https:\/\/www.carl-abrc.ca\/fr\/","name":"Association des biblioth\u00e8ques de recherche du Canada","description":"ABRC","publisher":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carl-abrc.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization","name":"Association des biblioth\u00e8ques de recherche du Canada","url":"https:\/\/www.carl-abrc.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/07\/cropped-Stacked_Colour_L.png","contentUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/07\/cropped-Stacked_Colour_L.png","width":641,"height":250,"caption":"Association des biblioth\u00e8ques de recherche du Canada"},"image":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/carlabrc"]},{"@type":"Person","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/person\/d9b6bfb73c89f6e9eafbd338013764ed","name":"Julie Morin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8f563df894a5ea8e4663aea014d75f7ff272a49a318995c22006e48ba2fca63e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8f563df894a5ea8e4663aea014d75f7ff272a49a318995c22006e48ba2fca63e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8f563df894a5ea8e4663aea014d75f7ff272a49a318995c22006e48ba2fca63e?s=96&d=mm&r=g","caption":"Julie Morin"},"url":"https:\/\/www.carl-abrc.ca\/fr\/author\/julie\/"}]}},"_links":{"self":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts\/27540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/comments?post=27540"}],"version-history":[{"count":0,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts\/27540\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/media?parent=27540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/categories?post=27540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/tags?post=27540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}