{"id":2856,"date":"2016-02-25T17:00:16","date_gmt":"2016-02-25T22:00:16","guid":{"rendered":"http:\/\/www.carl-abrc.ca\/fr\/?p=2856"},"modified":"2021-10-04T11:11:08","modified_gmt":"2021-10-04T15:11:08","slug":"nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne","status":"publish","type":"post","link":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/","title":{"rendered":"Nouvelle publication de l&rsquo;ABRC : Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne"},"content":{"rendered":"<p><strong>25 f\u00e9vrier 2016.<\/strong> \u2013 L&rsquo;Association des biblioth\u00e8ques de recherche du Canada vient de publier un nouvel expos\u00e9 de position, \u00ab <a href=\"http:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2016\/04\/Univ_can_editions_perennes_2016.pdf\">Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne<\/a> \u00bb, par Martha Whitehead et Brian Owen. L&rsquo;introduction de ce document le r\u00e9sume le mieux :<\/p>\n<blockquote>\n<p style=\"text-index: 40px;\"><em>Le milieu canadien des communications savantes est \u00e0 l&rsquo;aube de changements transformateurs. De nombreux facteurs convergent : l&rsquo;incidence continue de la technologie num\u00e9rique sur l&rsquo;enseignement et la recherche, l&rsquo;expertise sans cesse croissante des biblioth\u00e8ques universitaires en mati\u00e8re d&rsquo;utilisation et d&rsquo;appui des initiatives technologiques, le passage aux politiques sur le libre acc\u00e8s, l&rsquo;oligopole des \u00e9diteurs universitaires internationaux et les contraintes financi\u00e8res des budgets universitaires.<\/em><\/p>\n<p style=\"text-index: 40px;\"><em>Au Canada et dans le reste du monde, les universit\u00e9s doivent\u2028choisir la meilleure fa\u00e7on d&rsquo;investir dans les communications\u2028savantes pour appuyer la recherche \u00e0 l&rsquo;heure actuelle. Le\u2028pr\u00e9sent document vise \u00e0 d\u00e9crire les enjeux et les voies possibles, aux fins de discussion et de planification avec des chercheurs et des administrateurs d&rsquo;universit\u00e9s canadiennes dans le contexte international. Notre objectif commun consiste \u00e0 permettre de diffuser largement les r\u00e9sultats de recherche et de les rendre aussi accessibles que possible, \u00e0 l&rsquo;\u00e9chelle internationale, \u00e0 l&rsquo;aide de moyens de publication de grande qualit\u00e9 au co\u00fbt le plus bas possible.<\/em><\/p><\/blockquote>\n<p>Deux des priorit\u00e9s strat\u00e9giques de l&rsquo;ABRC sont de favoriser la cr\u00e9ation de nouvelles connaissances et la communication savante durable, y compris le libre acc\u00e8s, et encourager le r\u00f4le de la biblioth\u00e8que dans l&rsquo;\u00e9dition; et de faciliter la collaboration pour cr\u00e9er, acqu\u00e9rir, partager, et pr\u00e9server les ressources de recherche du Canada. Cet expos\u00e9 de position se veut un document d&rsquo;encadrement pour susciter des discussions et des d\u00e9marches collaboratives pour soutenir ces deux priorit\u00e9s strat\u00e9giques.<\/p>\n<p><strong>\u00c0 propos des auteurs<\/strong><\/p>\n<p><strong>Martha Whitehead<\/strong> est pr\u00e9sidente de l&rsquo;ABRC, et vice-rectrice et biblioth\u00e9caire en chef de la Queen&rsquo;s University. <strong>Brian Owen<\/strong> est biblioth\u00e9caire universitaire adjoint \u00e0 la biblioth\u00e8que de la Simon Fraser University (SFU), adjoint au Canadian Institute for Studies in Publishing de la SFU et au programme de ma\u00eetrise en publication de la SFU, et directeur g\u00e9n\u00e9ral du Public Knowledge Project (PKP).<\/p>\n<p>&gt; Le texte int\u00e9gral fran\u00e7ais: <a title=\"Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne\" href=\"http:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2016\/04\/Univ_can_editions_perennes_2016.pdf\">Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne (PDF)<\/a><\/p>\n<p>&gt; Le texte int\u00e9gral anglais: <a title=\"Canadian Universities and Sustainable Publishing\" href=\"http:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2016\/04\/Can_Univ_Sustainable_Publishing_2016.pdf\">Canadian Universities and Sustainable Publishing (PDF)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>25 f\u00e9vrier 2016. \u2013 L&rsquo;Association des biblioth\u00e8ques de recherche du Canada vient de publier un nouvel expos\u00e9 de position, \u00ab Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne \u00bb, par Martha Whitehead et [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":36194,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouvelle publication de l&#039;ABRC : Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne - Association des biblioth\u00e8ques de recherche du Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelle publication de l&#039;ABRC : Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne - Association des biblioth\u00e8ques de recherche du Canada\" \/>\n<meta property=\"og:description\" content=\"25 f\u00e9vrier 2016. \u2013 L&rsquo;Association des biblioth\u00e8ques de recherche du Canada vient de publier un nouvel expos\u00e9 de position, \u00ab Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne \u00bb, par Martha Whitehead et [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/\" \/>\n<meta property=\"og:site_name\" content=\"Association des biblioth\u00e8ques de recherche du Canada\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-25T22:00:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-04T15:11:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Katherine McColgan\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Katherine McColgan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\\\/\"},\"author\":{\"name\":\"Katherine McColgan\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/person\\\/0e28bc352eb584524dabf890f7141390\"},\"headline\":\"Nouvelle publication de l&rsquo;ABRC : Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne\",\"datePublished\":\"2016-02-25T22:00:16+00:00\",\"dateModified\":\"2021-10-04T15:11:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\\\/\"},\"wordCount\":417,\"publisher\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/NewsFeaturedImage-1.jpg\",\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\\\/\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\\\/\",\"name\":\"Nouvelle publication de l'ABRC : Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne - Association des biblioth\u00e8ques de recherche du Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/NewsFeaturedImage-1.jpg\",\"datePublished\":\"2016-02-25T22:00:16+00:00\",\"dateModified\":\"2021-10-04T15:11:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/NewsFeaturedImage-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/NewsFeaturedImage-1.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"C.A.R.L. Logo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/home-3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelle publication de l&rsquo;ABRC : Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/\",\"name\":\"Association des biblioth\u00e8ques de recherche du Canada\",\"description\":\"ABRC\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\",\"name\":\"Association des biblioth\u00e8ques de recherche du Canada\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Stacked_Colour_L.png\",\"contentUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Stacked_Colour_L.png\",\"width\":641,\"height\":250,\"caption\":\"Association des biblioth\u00e8ques de recherche du Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/carlabrc\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/person\\\/0e28bc352eb584524dabf890f7141390\",\"name\":\"Katherine McColgan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d8770eea9a07ba623ec853aca1456d4292fa99407780727a6fd6eab3c3fc1ef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d8770eea9a07ba623ec853aca1456d4292fa99407780727a6fd6eab3c3fc1ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d8770eea9a07ba623ec853aca1456d4292fa99407780727a6fd6eab3c3fc1ef?s=96&d=mm&r=g\",\"caption\":\"Katherine McColgan\"},\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/author\\\/katherine\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvelle publication de l'ABRC : Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne - Association des biblioth\u00e8ques de recherche du Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvelle publication de l'ABRC : Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne - Association des biblioth\u00e8ques de recherche du Canada","og_description":"25 f\u00e9vrier 2016. \u2013 L&rsquo;Association des biblioth\u00e8ques de recherche du Canada vient de publier un nouvel expos\u00e9 de position, \u00ab Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne \u00bb, par Martha Whitehead et [&hellip;]","og_url":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/","og_site_name":"Association des biblioth\u00e8ques de recherche du Canada","article_published_time":"2016-02-25T22:00:16+00:00","article_modified_time":"2021-10-04T15:11:08+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","type":"image\/jpeg"}],"author":"Katherine McColgan","twitter_misc":{"\u00c9crit par":"Katherine McColgan","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/#article","isPartOf":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/"},"author":{"name":"Katherine McColgan","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/person\/0e28bc352eb584524dabf890f7141390"},"headline":"Nouvelle publication de l&rsquo;ABRC : Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne","datePublished":"2016-02-25T22:00:16+00:00","dateModified":"2021-10-04T15:11:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/"},"wordCount":417,"publisher":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization"},"image":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/","url":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/","name":"Nouvelle publication de l'ABRC : Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne - Association des biblioth\u00e8ques de recherche du Canada","isPartOf":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/#primaryimage"},"image":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","datePublished":"2016-02-25T22:00:16+00:00","dateModified":"2021-10-04T15:11:08+00:00","breadcrumb":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/#primaryimage","url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","contentUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","width":1920,"height":1080,"caption":"C.A.R.L. Logo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/nouvelle-publication-de-labrc-universites-canadiennes-et-edition-perenne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carl-abrc.ca\/fr\/home-3\/"},{"@type":"ListItem","position":2,"name":"Nouvelle publication de l&rsquo;ABRC : Universit\u00e9s canadiennes et \u00e9dition p\u00e9renne"}]},{"@type":"WebSite","@id":"https:\/\/www.carl-abrc.ca\/fr\/#website","url":"https:\/\/www.carl-abrc.ca\/fr\/","name":"Association des biblioth\u00e8ques de recherche du Canada","description":"ABRC","publisher":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carl-abrc.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization","name":"Association des biblioth\u00e8ques de recherche du Canada","url":"https:\/\/www.carl-abrc.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/07\/cropped-Stacked_Colour_L.png","contentUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/07\/cropped-Stacked_Colour_L.png","width":641,"height":250,"caption":"Association des biblioth\u00e8ques de recherche du Canada"},"image":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/carlabrc"]},{"@type":"Person","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/person\/0e28bc352eb584524dabf890f7141390","name":"Katherine McColgan","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9d8770eea9a07ba623ec853aca1456d4292fa99407780727a6fd6eab3c3fc1ef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9d8770eea9a07ba623ec853aca1456d4292fa99407780727a6fd6eab3c3fc1ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d8770eea9a07ba623ec853aca1456d4292fa99407780727a6fd6eab3c3fc1ef?s=96&d=mm&r=g","caption":"Katherine McColgan"},"url":"https:\/\/www.carl-abrc.ca\/fr\/author\/katherine\/"}]}},"_links":{"self":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts\/2856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/comments?post=2856"}],"version-history":[{"count":0,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts\/2856\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/media\/36194"}],"wp:attachment":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/media?parent=2856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/categories?post=2856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/tags?post=2856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}