{"id":29723,"date":"2022-03-18T15:45:27","date_gmt":"2022-03-18T19:45:27","guid":{"rendered":"https:\/\/www.carl-abrc.ca\/?p=29723"},"modified":"2022-03-18T15:45:27","modified_gmt":"2022-03-18T19:45:27","slug":"labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc","status":"publish","type":"post","link":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/","title":{"rendered":"L&rsquo;ABRC accueille Karen Nicholson en tant que nouvelle agente principale de programme de l&rsquo;ABRC"},"content":{"rendered":"<p><strong>18 mars, 2022<\/strong> &#8211; L\u2019ABRC est heureuse d&rsquo;accueillir Karen Nicholson, qui se joindra \u00e0 l&rsquo;\u00e9quipe de l&rsquo;ABRC le 21 mars pour un d\u00e9tachement \u00e0 temps plein d&rsquo;un an de son poste de gestionnaire, ma\u00eetrise de l&rsquo;information, \u00e0 la biblioth\u00e8que McLaughlin de l&rsquo;Universit\u00e9 de Guelph.<\/p>\n<p>Karen Nicholson est biblioth\u00e9caire universitaire avec plus de vingt ans d&rsquo;exp\u00e9rience et enseignante \u00e0 la facult\u00e9 d&rsquo;\u00e9tudes sur l&rsquo;information et les m\u00e9dias de l&rsquo;Universit\u00e9 Western. Elle est titulaire d&rsquo;un doctorat (BSI) de Western et d&rsquo;une ma\u00eetrise et d&rsquo;une M.B.S.I. de McGill. Ses recherches portent sur la ma\u00eetrise de l&rsquo;information, les biblioth\u00e8ques universitaires et l&rsquo;enseignement sup\u00e9rieur, et elle a publi\u00e9 dans <em>The Library Quarterly<\/em>, <em>Journal of Documentation<\/em>, <em>College &amp; Research Libraries<\/em> et <em>Library Trends<\/em>.<\/p>\n<p>En tant qu&rsquo;agente principale de programme de l&rsquo;ABRC, Karen soutiendra le Comit\u00e9 sur l&rsquo;avancement de la recherche et ses groupes de travail et, en collaboration avec ces groupes et les agents de programme invit\u00e9s, jouera un r\u00f4le de premier plan dans la planification et la mise en \u0153uvre des initiatives de l&rsquo;ABRC dans les domaines des communications savantes, des d\u00e9p\u00f4ts ouverts, et de l\u2019acc\u00e8s durable. Karen participera \u00e9galement au d\u00e9veloppement de contenu Web, aux m\u00e9dias sociaux et \u00e0 la production du bulletin d&rsquo;information hebdomadaire de l&rsquo;ABRC, le Cyberavis.<\/p>\n<p>L&rsquo;ABRC aimerait profiter de cette occasion pour souhaiter la bienvenue \u00e0 Karen et remercier l&rsquo;Universit\u00e9 de Guelph d&rsquo;avoir soutenu ce d\u00e9tachement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>18 mars, 2022 &#8211; L\u2019ABRC est heureuse d&rsquo;accueillir Karen Nicholson, qui se joindra \u00e0 l&rsquo;\u00e9quipe de l&rsquo;ABRC le 21 mars pour un d\u00e9tachement \u00e0 temps plein d&rsquo;un an de son [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":36194,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-29723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;ABRC accueille Karen Nicholson en tant que nouvelle agente principale de programme de l&#039;ABRC - Association des biblioth\u00e8ques de recherche du Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;ABRC accueille Karen Nicholson en tant que nouvelle agente principale de programme de l&#039;ABRC - Association des biblioth\u00e8ques de recherche du Canada\" \/>\n<meta property=\"og:description\" content=\"18 mars, 2022 &#8211; L\u2019ABRC est heureuse d&rsquo;accueillir Karen Nicholson, qui se joindra \u00e0 l&rsquo;\u00e9quipe de l&rsquo;ABRC le 21 mars pour un d\u00e9tachement \u00e0 temps plein d&rsquo;un an de son [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/\" \/>\n<meta property=\"og:site_name\" content=\"Association des biblioth\u00e8ques de recherche du Canada\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-18T19:45:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julie Morin\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julie Morin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\\\/\"},\"author\":{\"name\":\"Julie Morin\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/person\\\/d9b6bfb73c89f6e9eafbd338013764ed\"},\"headline\":\"L&rsquo;ABRC accueille Karen Nicholson en tant que nouvelle agente principale de programme de l&rsquo;ABRC\",\"datePublished\":\"2022-03-18T19:45:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\\\/\"},\"wordCount\":280,\"publisher\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/NewsFeaturedImage-1.jpg\",\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\\\/\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\\\/\",\"name\":\"L'ABRC accueille Karen Nicholson en tant que nouvelle agente principale de programme de l'ABRC - Association des biblioth\u00e8ques de recherche du Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/NewsFeaturedImage-1.jpg\",\"datePublished\":\"2022-03-18T19:45:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/NewsFeaturedImage-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/NewsFeaturedImage-1.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"C.A.R.L. Logo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;ABRC accueille Karen Nicholson en tant que nouvelle agente principale de programme de l&rsquo;ABRC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/\",\"name\":\"Association des biblioth\u00e8ques de recherche du Canada\",\"description\":\"ABRC\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\",\"name\":\"Association des biblioth\u00e8ques de recherche du Canada\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Stacked_Colour_L.png\",\"contentUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Stacked_Colour_L.png\",\"width\":641,\"height\":250,\"caption\":\"Association des biblioth\u00e8ques de recherche du Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/carlabrc\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/person\\\/d9b6bfb73c89f6e9eafbd338013764ed\",\"name\":\"Julie Morin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f563df894a5ea8e4663aea014d75f7ff272a49a318995c22006e48ba2fca63e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f563df894a5ea8e4663aea014d75f7ff272a49a318995c22006e48ba2fca63e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f563df894a5ea8e4663aea014d75f7ff272a49a318995c22006e48ba2fca63e?s=96&d=mm&r=g\",\"caption\":\"Julie Morin\"},\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/author\\\/julie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'ABRC accueille Karen Nicholson en tant que nouvelle agente principale de programme de l'ABRC - Association des biblioth\u00e8ques de recherche du Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/","og_locale":"fr_FR","og_type":"article","og_title":"L'ABRC accueille Karen Nicholson en tant que nouvelle agente principale de programme de l'ABRC - Association des biblioth\u00e8ques de recherche du Canada","og_description":"18 mars, 2022 &#8211; L\u2019ABRC est heureuse d&rsquo;accueillir Karen Nicholson, qui se joindra \u00e0 l&rsquo;\u00e9quipe de l&rsquo;ABRC le 21 mars pour un d\u00e9tachement \u00e0 temps plein d&rsquo;un an de son [&hellip;]","og_url":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/","og_site_name":"Association des biblioth\u00e8ques de recherche du Canada","article_published_time":"2022-03-18T19:45:27+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","type":"image\/jpeg"}],"author":"Julie Morin","twitter_misc":{"\u00c9crit par":"Julie Morin","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/#article","isPartOf":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/"},"author":{"name":"Julie Morin","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/person\/d9b6bfb73c89f6e9eafbd338013764ed"},"headline":"L&rsquo;ABRC accueille Karen Nicholson en tant que nouvelle agente principale de programme de l&rsquo;ABRC","datePublished":"2022-03-18T19:45:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/"},"wordCount":280,"publisher":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization"},"image":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/","url":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/","name":"L'ABRC accueille Karen Nicholson en tant que nouvelle agente principale de programme de l'ABRC - Association des biblioth\u00e8ques de recherche du Canada","isPartOf":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/#primaryimage"},"image":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","datePublished":"2022-03-18T19:45:27+00:00","breadcrumb":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/#primaryimage","url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","contentUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","width":1920,"height":1080,"caption":"C.A.R.L. Logo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/labrc-accueille-karen-nicholson-en-tant-que-nouvelle-agente-principale-de-programme-de-labrc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carl-abrc.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;ABRC accueille Karen Nicholson en tant que nouvelle agente principale de programme de l&rsquo;ABRC"}]},{"@type":"WebSite","@id":"https:\/\/www.carl-abrc.ca\/fr\/#website","url":"https:\/\/www.carl-abrc.ca\/fr\/","name":"Association des biblioth\u00e8ques de recherche du Canada","description":"ABRC","publisher":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carl-abrc.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization","name":"Association des biblioth\u00e8ques de recherche du Canada","url":"https:\/\/www.carl-abrc.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/07\/cropped-Stacked_Colour_L.png","contentUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/07\/cropped-Stacked_Colour_L.png","width":641,"height":250,"caption":"Association des biblioth\u00e8ques de recherche du Canada"},"image":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/carlabrc"]},{"@type":"Person","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/person\/d9b6bfb73c89f6e9eafbd338013764ed","name":"Julie Morin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8f563df894a5ea8e4663aea014d75f7ff272a49a318995c22006e48ba2fca63e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8f563df894a5ea8e4663aea014d75f7ff272a49a318995c22006e48ba2fca63e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8f563df894a5ea8e4663aea014d75f7ff272a49a318995c22006e48ba2fca63e?s=96&d=mm&r=g","caption":"Julie Morin"},"url":"https:\/\/www.carl-abrc.ca\/fr\/author\/julie\/"}]}},"_links":{"self":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts\/29723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/comments?post=29723"}],"version-history":[{"count":0,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts\/29723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/media\/36194"}],"wp:attachment":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/media?parent=29723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/categories?post=29723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/tags?post=29723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}