{"id":36480,"date":"2025-01-22T16:16:08","date_gmt":"2025-01-22T21:16:08","guid":{"rendered":"https:\/\/www.carl-abrc.ca\/?p=36480"},"modified":"2025-01-22T16:16:08","modified_gmt":"2025-01-22T21:16:08","slug":"appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc","status":"publish","type":"post","link":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/","title":{"rendered":"Appel \u00e0 manifestation d\u2019int\u00e9r\u00eat : Comit\u00e9 directeur, Communaut\u00e9 de pratique en communication de l\u2019ABRC"},"content":{"rendered":"<p><strong>22 janvier 2025<\/strong> &#8211; <span style=\"font-weight: 300;\">L\u2019Association des biblioth\u00e8ques de recherche du Canada (ABRC) est \u00e0 la recherche de 2 \u00e0 3 repr\u00e9sentants additionnels qui travaillent dans une institution universitaire canadienne pour se joindre au <\/span><b>Comit\u00e9 directeur de la Communaut\u00e9 de pratique en communication. <\/b><span style=\"font-weight: 300;\">Les membres ont g\u00e9n\u00e9ralement un mandat d\u2019un an et doivent \u00eatre en mesure de consacrer 5 \u00e0 10 heures par mois \u00e0 l&rsquo;avancement des travaux de l&rsquo;\u00e9quipe.<\/span><\/p>\n<h2>Contexte<\/h2>\n<p><span style=\"font-weight: 300;\">Cr\u00e9\u00e9e en 2022, la Communaut\u00e9 de pratique (CdP) en communication rassemble des biblioth\u00e9caires et d&rsquo;autres coll\u00e8gues d&rsquo;\u00e9tablissements universitaires canadiens qui travaillent dans le domaine des communications ou s&rsquo;y int\u00e9ressent. Les objectifs de la CdP sont de cr\u00e9er des liens, d&rsquo;assurer le partage d&rsquo;informations et d&rsquo;accro\u00eetre l&rsquo;expertise et les capacit\u00e9s \u00e0 travers le Canada. Le comit\u00e9 directeur se r\u00e9unit tous les mois pour organiser des appels communautaires, des tables rondes, des ateliers et\/ou d&rsquo;autres formes d&rsquo;engagement communautaire. Ils ont lieu deux fois par trimestre (environ 4 fois par ann\u00e9e acad\u00e9mique). Ils cr\u00e9ent \u00e9galement des ressources pour la communaut\u00e9 de pratique et y donnent acc\u00e8s dans le cadre de leurs activit\u00e9s (ressources partag\u00e9es, liens vers des pr\u00e9sentations, etc.).\u00a0 De plus amples informations sont disponibles dans le <\/span><a href=\"https:\/\/docs.google.com\/document\/d\/e\/2PACX-1vSQXg7iKntslIYSe-uIYVddEbAfLG4bPnsADnpVKkGibQ3IiZBlQLCwicAt92kVx1SHmYzUsRRm77RB\/pub\"><span style=\"font-weight: 300;\">mandat du comit\u00e9<\/span><\/a><span style=\"font-weight: 300;\">.<\/span><\/p>\n<h2>Instructions<\/h2>\n<p><span style=\"font-weight: 300;\">Pour poser votre candidature, veuillez envoyer une br\u00e8ve description de votre int\u00e9r\u00eat \u00e0 faire partie de ce groupe et de votre exp\u00e9rience dans le domaine des communications \u00e0 Taleen Aktorosian, agente de communication et de projet de l&rsquo;ABRC, <\/span><a href=\"mailto:taleen.aktorosian@carl-abrc.ca\"><span style=\"font-weight: 300;\">taleen.aktorosian@carl-abrc.ca<\/span><\/a><span style=\"font-weight: 300;\">, d\u2019ici le <\/span><b>14 f\u00e9vrier 2025. <\/b><span style=\"font-weight: 300;\">Les membres seront choisis par les copr\u00e9sidentes du comit\u00e9 directeur, Lisa Abrams et Kristine Power dans le but d&rsquo;assurer la diversit\u00e9 des membres en fonction de la taille et de l&#8217;emplacement des \u00e9tablissements, des connaissances, de l&rsquo;exp\u00e9rience ou des responsabilit\u00e9s, et de leur stade de carri\u00e8re. \u00c0 l&rsquo;heure actuelle, nous accueillons avec int\u00e9r\u00eat les personnes provenant de biblioth\u00e8ques membres ou non de l&rsquo;ABRC, ainsi que les personnes provenant d&rsquo;institutions francophones.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>22 janvier 2025 &#8211; L\u2019Association des biblioth\u00e8ques de recherche du Canada (ABRC) est \u00e0 la recherche de 2 \u00e0 3 repr\u00e9sentants additionnels qui travaillent dans une institution universitaire canadienne pour [&hellip;]<\/p>\n","protected":false},"author":131,"featured_media":36193,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-36480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Appel \u00e0 manifestation d\u2019int\u00e9r\u00eat : Comit\u00e9 directeur, Communaut\u00e9 de pratique en communication de l\u2019ABRC - Association des biblioth\u00e8ques de recherche du Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Appel \u00e0 manifestation d\u2019int\u00e9r\u00eat : Comit\u00e9 directeur, Communaut\u00e9 de pratique en communication de l\u2019ABRC - Association des biblioth\u00e8ques de recherche du Canada\" \/>\n<meta property=\"og:description\" content=\"22 janvier 2025 &#8211; L\u2019Association des biblioth\u00e8ques de recherche du Canada (ABRC) est \u00e0 la recherche de 2 \u00e0 3 repr\u00e9sentants additionnels qui travaillent dans une institution universitaire canadienne pour [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/\" \/>\n<meta property=\"og:site_name\" content=\"Association des biblioth\u00e8ques de recherche du Canada\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-22T21:16:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Taleen Aktorosian\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Taleen Aktorosian\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\\\/\"},\"author\":{\"name\":\"Taleen Aktorosian\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/person\\\/0249489ce3cdcef7d6e8d117510a9fb3\"},\"headline\":\"Appel \u00e0 manifestation d\u2019int\u00e9r\u00eat : Comit\u00e9 directeur, Communaut\u00e9 de pratique en communication de l\u2019ABRC\",\"datePublished\":\"2025-01-22T21:16:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\\\/\"},\"wordCount\":366,\"publisher\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/NewsFeaturedImage-1.jpg\",\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\\\/\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\\\/\",\"name\":\"Appel \u00e0 manifestation d\u2019int\u00e9r\u00eat : Comit\u00e9 directeur, Communaut\u00e9 de pratique en communication de l\u2019ABRC - Association des biblioth\u00e8ques de recherche du Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/NewsFeaturedImage-1.jpg\",\"datePublished\":\"2025-01-22T21:16:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/NewsFeaturedImage-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/NewsFeaturedImage-1.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"C.A.R.L. Logo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/nouvelles\\\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/home-3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Appel \u00e0 manifestation d\u2019int\u00e9r\u00eat : Comit\u00e9 directeur, Communaut\u00e9 de pratique en communication de l\u2019ABRC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/\",\"name\":\"Association des biblioth\u00e8ques de recherche du Canada\",\"description\":\"ABRC\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\",\"name\":\"Association des biblioth\u00e8ques de recherche du Canada\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Stacked_Colour_L.png\",\"contentUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Stacked_Colour_L.png\",\"width\":641,\"height\":250,\"caption\":\"Association des biblioth\u00e8ques de recherche du Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/carlabrc\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/person\\\/0249489ce3cdcef7d6e8d117510a9fb3\",\"name\":\"Taleen Aktorosian\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1b9ed12420a3a1e0f083aa2522c618cebd777c8170eaf61dac438cba806f2cc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1b9ed12420a3a1e0f083aa2522c618cebd777c8170eaf61dac438cba806f2cc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1b9ed12420a3a1e0f083aa2522c618cebd777c8170eaf61dac438cba806f2cc?s=96&d=mm&r=g\",\"caption\":\"Taleen Aktorosian\"},\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/author\\\/taleen-aktorosian\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Appel \u00e0 manifestation d\u2019int\u00e9r\u00eat : Comit\u00e9 directeur, Communaut\u00e9 de pratique en communication de l\u2019ABRC - Association des biblioth\u00e8ques de recherche du Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/","og_locale":"fr_FR","og_type":"article","og_title":"Appel \u00e0 manifestation d\u2019int\u00e9r\u00eat : Comit\u00e9 directeur, Communaut\u00e9 de pratique en communication de l\u2019ABRC - Association des biblioth\u00e8ques de recherche du Canada","og_description":"22 janvier 2025 &#8211; L\u2019Association des biblioth\u00e8ques de recherche du Canada (ABRC) est \u00e0 la recherche de 2 \u00e0 3 repr\u00e9sentants additionnels qui travaillent dans une institution universitaire canadienne pour [&hellip;]","og_url":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/","og_site_name":"Association des biblioth\u00e8ques de recherche du Canada","article_published_time":"2025-01-22T21:16:08+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","type":"image\/jpeg"}],"author":"Taleen Aktorosian","twitter_misc":{"\u00c9crit par":"Taleen Aktorosian","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/#article","isPartOf":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/"},"author":{"name":"Taleen Aktorosian","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/person\/0249489ce3cdcef7d6e8d117510a9fb3"},"headline":"Appel \u00e0 manifestation d\u2019int\u00e9r\u00eat : Comit\u00e9 directeur, Communaut\u00e9 de pratique en communication de l\u2019ABRC","datePublished":"2025-01-22T21:16:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/"},"wordCount":366,"publisher":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization"},"image":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/","url":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/","name":"Appel \u00e0 manifestation d\u2019int\u00e9r\u00eat : Comit\u00e9 directeur, Communaut\u00e9 de pratique en communication de l\u2019ABRC - Association des biblioth\u00e8ques de recherche du Canada","isPartOf":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/#primaryimage"},"image":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","datePublished":"2025-01-22T21:16:08+00:00","breadcrumb":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/#primaryimage","url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","contentUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/09\/NewsFeaturedImage-1.jpg","width":1920,"height":1080,"caption":"C.A.R.L. Logo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.carl-abrc.ca\/fr\/nouvelles\/appel-a-manifestation-dinteret-comite-directeur-communaute-de-pratique-en-communication-de-labrc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carl-abrc.ca\/fr\/home-3\/"},{"@type":"ListItem","position":2,"name":"Appel \u00e0 manifestation d\u2019int\u00e9r\u00eat : Comit\u00e9 directeur, Communaut\u00e9 de pratique en communication de l\u2019ABRC"}]},{"@type":"WebSite","@id":"https:\/\/www.carl-abrc.ca\/fr\/#website","url":"https:\/\/www.carl-abrc.ca\/fr\/","name":"Association des biblioth\u00e8ques de recherche du Canada","description":"ABRC","publisher":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carl-abrc.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization","name":"Association des biblioth\u00e8ques de recherche du Canada","url":"https:\/\/www.carl-abrc.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/07\/cropped-Stacked_Colour_L.png","contentUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/07\/cropped-Stacked_Colour_L.png","width":641,"height":250,"caption":"Association des biblioth\u00e8ques de recherche du Canada"},"image":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/carlabrc"]},{"@type":"Person","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/person\/0249489ce3cdcef7d6e8d117510a9fb3","name":"Taleen Aktorosian","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a1b9ed12420a3a1e0f083aa2522c618cebd777c8170eaf61dac438cba806f2cc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a1b9ed12420a3a1e0f083aa2522c618cebd777c8170eaf61dac438cba806f2cc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a1b9ed12420a3a1e0f083aa2522c618cebd777c8170eaf61dac438cba806f2cc?s=96&d=mm&r=g","caption":"Taleen Aktorosian"},"url":"https:\/\/www.carl-abrc.ca\/fr\/author\/taleen-aktorosian\/"}]}},"_links":{"self":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts\/36480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/users\/131"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/comments?post=36480"}],"version-history":[{"count":1,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts\/36480\/revisions"}],"predecessor-version":[{"id":38563,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/posts\/36480\/revisions\/38563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/media\/36193"}],"wp:attachment":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/media?parent=36480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/categories?post=36480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/tags?post=36480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}