{"id":40464,"date":"2026-03-16T14:50:15","date_gmt":"2026-03-16T18:50:15","guid":{"rendered":"https:\/\/www.carl-abrc.ca\/?post_type=tribe_events&#038;p=40464"},"modified":"2026-03-19T09:39:05","modified_gmt":"2026-03-19T13:39:05","slug":"projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2","status":"publish","type":"tribe_events","link":"https:\/\/www.carl-abrc.ca\/fr\/evenement\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\/","title":{"rendered":"Projet d\u2019\u00e9valuation comparative DPC RAM au niveau national : webinaire de lancement [EN ANGLAIS]"},"content":{"rendered":"<p>Date: <strong>7 avril 2026<\/strong><br \/>\nHeure: <strong>13h00 &#8211; 14h00 HE<\/strong><\/p>\n<p><a href=\"https:\/\/us02web.zoom.us\/meeting\/register\/CthHvSCkRX6aV0o8LcRJuA\">Inscription<\/a><\/p>\n<p>\u00cates-vous int\u00e9ress\u00e9 \u00e0 d\u00e9velopper les capacit\u00e9s de pr\u00e9servation num\u00e9rique de votre organisation? Joignez-vous \u00e0 la deuxi\u00e8me phase du <a href=\"https:\/\/www.carl-abrc.ca\/fr\/faire-avancer-la-recherche\/preservation\/#dpc-ram-evaluation-comparative\">Projet national d\u2019\u00e9valuation DPC RAM<\/a>, coordonn\u00e9 par l\u2019Association des biblioth\u00e8ques de recherche du Canada (ABRC). Ce projet permet aux institutions canadiennes engag\u00e9es dans la pr\u00e9servation num\u00e9rique, quel que soit leur niveau de maturit\u00e9, de renforcer collectivement leurs capacit\u00e9s, d\u2019\u00e9tablir des objectifs d\u2019am\u00e9lioration continue et de contribuer \u00e0 un portrait de l\u2019\u00e9tat actuel de la pr\u00e9servation num\u00e9rique au Canada.<\/p>\n<p><em>Pourquoi l\u2019\u00e9valuation comparative ?<\/em><\/p>\n<p>L\u2019\u00e9valuation comparative des capacit\u00e9s est essentielle \u00e0 l\u2019am\u00e9lioration continue des programmes de pr\u00e9servation num\u00e9rique. Que votre institution d\u00e9bute tout juste ou qu\u2019elle m\u00e8ne des activit\u00e9s de pr\u00e9servation num\u00e9rique depuis un certain temps, l\u2019\u00e9valuation offre l\u2019occasion de situer votre organisation et d\u2019identifier les domaines dans lesquels elle peut \u00e9voluer.<\/p>\n<p><em>Qu\u2019est-ce que le DPC RAM ?<\/em><\/p>\n<p>Le Rapid Assessment Model (RAM) de la Digital Preservation Coalition (DPC) est un outil de mod\u00e9lisation de la maturit\u00e9 en pr\u00e9servation num\u00e9rique qui permet d\u2019\u00e9valuer rapidement les capacit\u00e9s d\u2019une organisation dans ce domaine. Le mod\u00e8le est con\u00e7u pour \u00eatre accessible et adaptable \u00e0 un large \u00e9ventail d\u2019institutions et de contextes, et pour soutenir une am\u00e9lioration continue au fil du temps.<\/p>\n<p><em>Qui peut participer ?<\/em><\/p>\n<p>Les biblioth\u00e8ques, archives, d\u00e9p\u00f4ts, mus\u00e9es, galeries et autres organisations canadiennes engag\u00e9es dans la pr\u00e9servation num\u00e9rique \u00e0 tout niveau sont invit\u00e9es \u00e0 compl\u00e9ter l\u2019\u00e9valuation, ind\u00e9pendamment de leur adh\u00e9sion \u00e0 l\u2019ABRC. S\u2019il s\u2019agit de votre premier exercice d\u2019\u00e9valuation comparative, nous sommes l\u00e0 pour vous accompagner! Le <a href=\"https:\/\/www.carl-abrc.ca\/fr\/faire-avancer-la-recherche\/preservation\/preservation-numerique\/\">Groupe de travail sur la pr\u00e9servation num\u00e9rique (GT-PN)<\/a> de l\u2019ABRC offrira du soutien aux organisations qui r\u00e9alisent l\u2019\u00e9valuation en partageant des ressources et en organisant des s\u00e9ances de soutien.<\/p>\n<p>Les membres de l\u2019ABRC qui ont d\u00e9j\u00e0 soumis leurs r\u00e9sultats lors de la phase pilote du projet n\u2019ont pas besoin de les soumettre \u00e0 nouveau. Les soumissions de la phase pilote seront comptabilis\u00e9es dans le rapport final du projet.<\/p>\n<p>Joignez-vous \u00e0 nous pour une pr\u00e9sentation g\u00e9n\u00e9rale du projet, anim\u00e9e par Amanda Tom\u00e9, de l\u2019Alliance de recherche num\u00e9rique du Canada, et Sarah Lake, de l\u2019Universit\u00e9 Concordia et agente de programme invit\u00e9e de l\u2019ABRC pour la pr\u00e9servation num\u00e9rique. Le webinaire de lancement pr\u00e9sentera le contexte du projet et du DPC RAM, les ressources \u00e9labor\u00e9es par le GT-PN de l\u2019ABRC, le fonctionnement des s\u00e9ances de soutien. Une p\u00e9riode de questions sera pr\u00e9vue \u00e0 la suite de la pr\u00e9sentation.<\/p>\n<p>Ce webinaire se d\u00e9roulera en anglais. Une <a href=\"https:\/\/www.carl-abrc.ca\/fr\/evenement\/projet-devaluation-comparative-dpc-ram-au-niveau-nationale-webinaire-de-lancement-2\/\">s\u00e9ance en fran\u00e7ais<\/a> aura lieu le 8 avril de 14h00 \u00e0 15h00. Le webinaire en anglais comprendra une courte pr\u00e9sentation sur la DPC RAM par Anna Perricci, responsable de DPC Americas.<\/p>\n<p><em>Veuillez noter que les pr\u00e9sentations seront enregistr\u00e9es, mais pas la discussion.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Date: 7 avril 2026 Heure: 13h00 &#8211; 14h00 HE Inscription \u00cates-vous int\u00e9ress\u00e9 \u00e0 d\u00e9velopper les capacit\u00e9s de pr\u00e9servation num\u00e9rique de votre organisation? Joignez-vous \u00e0 la deuxi\u00e8me phase du Projet national [&hellip;]<\/p>\n","protected":false},"author":129,"featured_media":40687,"template":"","meta":{"_acf_changed":false,"_EventAllDay":false,"_EventTimezone":"America\/Toronto","_EventStartDate":"2026-04-07 13:00:00","_EventEndDate":"2026-04-07 14:00:00","_EventStartDateUTC":"2026-04-07 17:00:00","_EventEndDateUTC":"2026-04-07 18:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"$","_EventCurrencyCode":"CAD","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[37076],"_EventVenueID":[37071],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[117],"class_list":["post-40464","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-preservation-numerique","cat_preservation-numerique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projet d\u2019\u00e9valuation comparative DPC RAM au niveau national : webinaire de lancement [EN ANGLAIS] - Association des biblioth\u00e8ques de recherche du Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carl-abrc.ca\/fr\/evenement\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projet d\u2019\u00e9valuation comparative DPC RAM au niveau national : webinaire de lancement [EN ANGLAIS] - Association des biblioth\u00e8ques de recherche du Canada\" \/>\n<meta property=\"og:description\" content=\"Date: 7 avril 2026 Heure: 13h00 &#8211; 14h00 HE Inscription \u00cates-vous int\u00e9ress\u00e9 \u00e0 d\u00e9velopper les capacit\u00e9s de pr\u00e9servation num\u00e9rique de votre organisation? Joignez-vous \u00e0 la deuxi\u00e8me phase du Projet national [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carl-abrc.ca\/fr\/evenement\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Association des biblioth\u00e8ques de recherche du Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-19T13:39:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2026\/02\/Digital-Preservation-Graphic.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/evenement\\\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\\\/\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/evenement\\\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\\\/\",\"name\":\"Projet d\u2019\u00e9valuation comparative DPC RAM au niveau national : webinaire de lancement [EN ANGLAIS] - Association des biblioth\u00e8ques de recherche du Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/evenement\\\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/evenement\\\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Benchmarking.jpg\",\"datePublished\":\"2026-03-16T18:50:15+00:00\",\"dateModified\":\"2026-03-19T13:39:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/evenement\\\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/evenement\\\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/evenement\\\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Benchmarking.jpg\",\"contentUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Benchmarking.jpg\",\"width\":2000,\"height\":1125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/evenement\\\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/home-3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e9nements\",\"item\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/evenements\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Projet d\u2019\u00e9valuation comparative DPC RAM au niveau national : webinaire de lancement [EN ANGLAIS]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/\",\"name\":\"Association des biblioth\u00e8ques de recherche du Canada\",\"description\":\"ABRC\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#organization\",\"name\":\"Association des biblioth\u00e8ques de recherche du Canada\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Stacked_Colour_L.png\",\"contentUrl\":\"https:\\\/\\\/www.carl-abrc.ca\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Stacked_Colour_L.png\",\"width\":641,\"height\":250,\"caption\":\"Association des biblioth\u00e8ques de recherche du Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carl-abrc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/carlabrc\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projet d\u2019\u00e9valuation comparative DPC RAM au niveau national : webinaire de lancement [EN ANGLAIS] - Association des biblioth\u00e8ques de recherche du Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carl-abrc.ca\/fr\/evenement\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Projet d\u2019\u00e9valuation comparative DPC RAM au niveau national : webinaire de lancement [EN ANGLAIS] - Association des biblioth\u00e8ques de recherche du Canada","og_description":"Date: 7 avril 2026 Heure: 13h00 &#8211; 14h00 HE Inscription \u00cates-vous int\u00e9ress\u00e9 \u00e0 d\u00e9velopper les capacit\u00e9s de pr\u00e9servation num\u00e9rique de votre organisation? Joignez-vous \u00e0 la deuxi\u00e8me phase du Projet national [&hellip;]","og_url":"https:\/\/www.carl-abrc.ca\/fr\/evenement\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\/","og_site_name":"Association des biblioth\u00e8ques de recherche du Canada","article_modified_time":"2026-03-19T13:39:05+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2026\/02\/Digital-Preservation-Graphic.jpg","type":"image\/jpeg"}],"twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carl-abrc.ca\/fr\/evenement\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\/","url":"https:\/\/www.carl-abrc.ca\/fr\/evenement\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\/","name":"Projet d\u2019\u00e9valuation comparative DPC RAM au niveau national : webinaire de lancement [EN ANGLAIS] - Association des biblioth\u00e8ques de recherche du Canada","isPartOf":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/evenement\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\/#primaryimage"},"image":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/evenement\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2026\/03\/Benchmarking.jpg","datePublished":"2026-03-16T18:50:15+00:00","dateModified":"2026-03-19T13:39:05+00:00","breadcrumb":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/evenement\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carl-abrc.ca\/fr\/evenement\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carl-abrc.ca\/fr\/evenement\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\/#primaryimage","url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2026\/03\/Benchmarking.jpg","contentUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2026\/03\/Benchmarking.jpg","width":2000,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/www.carl-abrc.ca\/fr\/evenement\/projet-devaluation-comparative-dpc-ram-au-niveau-national-webinaire-de-lancement-en-anglais-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.carl-abrc.ca\/fr\/home-3\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e9nements","item":"https:\/\/www.carl-abrc.ca\/fr\/evenements\/"},{"@type":"ListItem","position":3,"name":"Projet d\u2019\u00e9valuation comparative DPC RAM au niveau national : webinaire de lancement [EN ANGLAIS]"}]},{"@type":"WebSite","@id":"https:\/\/www.carl-abrc.ca\/fr\/#website","url":"https:\/\/www.carl-abrc.ca\/fr\/","name":"Association des biblioth\u00e8ques de recherche du Canada","description":"ABRC","publisher":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carl-abrc.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carl-abrc.ca\/fr\/#organization","name":"Association des biblioth\u00e8ques de recherche du Canada","url":"https:\/\/www.carl-abrc.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/07\/cropped-Stacked_Colour_L.png","contentUrl":"https:\/\/www.carl-abrc.ca\/wp-content\/uploads\/2024\/07\/cropped-Stacked_Colour_L.png","width":641,"height":250,"caption":"Association des biblioth\u00e8ques de recherche du Canada"},"image":{"@id":"https:\/\/www.carl-abrc.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/carlabrc"]}]}},"_links":{"self":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/40464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/users\/129"}],"version-history":[{"count":3,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/40464\/revisions"}],"predecessor-version":[{"id":40526,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/40464\/revisions\/40526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/media\/40687"}],"wp:attachment":[{"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/media?parent=40464"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/tags?post=40464"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.carl-abrc.ca\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=40464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}